{"id":24614,"date":"2021-02-19T09:43:14","date_gmt":"2021-02-19T08:43:14","guid":{"rendered":"https:\/\/www.carpinteria-aluminio.cat\/?p=24614"},"modified":"2021-02-19T09:43:16","modified_gmt":"2021-02-19T08:43:16","slug":"beneficiat-de-les-persianes-intelligents","status":"publish","type":"post","link":"https:\/\/www.carpinteria-aluminio.cat\/ca\/beneficiat-de-les-persianes-intelligents\/","title":{"rendered":"Beneficia&#8217;t de les persianes intel\u00b7ligents"},"content":{"rendered":"\n<p>Per a qualsevol persona que construeixi o remodeli una casa, l&#8217;efici\u00e8ncia energ\u00e8tica \u00e9s un factor clau. Des de l&#8217;a\u00efllament fins a la ubicaci\u00f3, la manera de construir una casa pot tenir un impacte directe en la quantitat d&#8217;energia que consumeix. Encara que una casa que es mant\u00e9 confortable en totes les estacions de l&#8217;any sense emprar un sistema actiu de calefacci\u00f3 o refrigeraci\u00f3, pot ser un objectiu cost\u00f3s per a molta gent, hi ha una cosa relativament senzilla que pots afegir a la teva casa per a ajudar a controlar la temperatura de manera passiva: les persianes intel\u00b7ligents.<\/p>\n\n\n\n<p>Les persianes intel\u00b7ligents i motoritzades poden ajudar-te a controlar el guany de llum i la p\u00e8rdua de calor que la teva casa experimenta de manera natural al llarg del dia, simplement obrint-se i tancant-se a unes certes hores preprogramades. Amb la incorporaci\u00f3 de la tecnologia dom\u00e8stica intel\u00b7ligent, les persianes poden aprendre realment quan han d&#8217;obrir-se i tancar-se en funci\u00f3 de la temperatura i la llum solar, maximitzant l&#8217;efici\u00e8ncia energ\u00e8tica del seu sistema de climatitzaci\u00f3.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-scaled.jpg\" alt=\"\" class=\"wp-image-24531\" width=\"463\" height=\"463\" srcset=\"https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-scaled.jpg 2560w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-300x300.jpg 300w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-1024x1024.jpg 1024w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-150x150.jpg 150w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-768x768.jpg 768w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-1536x1536.jpg 1536w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-2048x2048.jpg 2048w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-146x146.jpg 146w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-50x50.jpg 50w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-75x75.jpg 75w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-85x85.jpg 85w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/persiana3-edited-80x80.jpg 80w\" sizes=\"auto, (max-width:767px) 463px, 463px\" \/><\/figure><\/div>\n\n\n\n<p>A continuaci\u00f3, t&#8217;ensenyem els avantatges de les persianes intel\u00b7ligents per a mostrar-te que s\u00f3n una bona opci\u00f3 per a la teva llar.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><p><strong>Comoditat<\/strong><\/p><\/li><\/ul>\n\n\n\n<p>Les persianes intel\u00b7ligents estan motoritzades, poden obrir-se i tancar-se simplement tocant un bot\u00f3, un comandament a dist\u00e0ncia o amb una simple aplicaci\u00f3 en un tel\u00e8fon intel\u00b7ligent. A m\u00e9s, la possibilitat d&#8217;establir horaris per a obrir-les i tancar-les en moments espec\u00edfics significa que, gr\u00e0cies a la seva intel\u00b7lig\u00e8ncia artificial, tal vegada mai tens la necessitat de preocupar-te per elles.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><p><strong>Estalvi d&#8217;energia<\/strong><\/p><\/li><\/ul>\n\n\n\n<p>La connexi\u00f3 de les persianes a una xarxa dom\u00e8stica intel\u00b7ligent ajuda a minimitzar la quantitat d&#8217;energia que utilitza la calefacci\u00f3, ventilaci\u00f3 i aire condicionat en permetre que les persianes reaccionin de manera independent a les lectures dels sensors de temperatura i llum solar que tamb\u00e9 estan connectats a la xarxa intel\u00b7ligent. En conseq\u00fc\u00e8ncia, les persianes sabran realment quan han de tancar-se durant la part m\u00e9s calorosa del dia per a reduir l&#8217;entrada de calor en la llar o si han d&#8217;obrir-se durant un dia assolellat a l&#8217;hivern per a permetre que el sol calent una habitaci\u00f3 de manera natural.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><div class=\"textarea-desti col-xs-12 col-sm-6\">\r\n<div class=\"form-control second-textarea\">Integraci\u00f3 amb la llar intel\u00b7ligent<\/div>\r\n<\/div><\/li><\/ul>\n\n\n\n<p>Els term\u00f2stats intel\u00b7ligents disposen d&#8217;una gran quantitat de dades per a determinar si obrir o tancar les persianes intel\u00b7ligents ajudar\u00e0 a reduir el consum d&#8217;energia, com l&#8217;hora del dia, el temps que fa en l&#8217;exterior i la temperatura de la casa. Utilitzant totes aquestes dades, aquest tipus de term\u00f2stat pot detectar que una habitaci\u00f3 s&#8217;est\u00e0 escalfant massa i tancar les persianes en lloc d&#8217;encendre l&#8217;aire condicionat o fer el contrari quan sap que una habitaci\u00f3 est\u00e0 m\u00e9s freda del que deuria.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><p><strong>Il\u00b7luminaci\u00f3 intel\u00b7ligent<\/strong><\/p><\/li><\/ul>\n\n\n\n<p>Quan es combinen amb la il\u00b7luminaci\u00f3 intel\u00b7ligent, les persianes intel\u00b7ligents poden ajudar a maximitzar la quantitat de llum natural a la teva casa per a reduir el consum d&#8217;electricitat. Per exemple, si s&#8217;obren les persianes es pot activar l&#8217;apagat de la il\u00b7luminaci\u00f3 intel\u00b7ligent, i viceversa.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><p><strong>Protecci\u00f3<\/strong><\/p><\/li><\/ul>\n\n\n\n<p>Com qualsevol mare o pare sap, l&#8217;abs\u00e8ncia de cordes en les persianes motoritzades \u00e9s un gran avantatge de seguretat: ja que no haur\u00e0s de preocupar-te de mantenir-les fora de l&#8217;abast dels teus fills. No obstant aix\u00f2, en una casa intel\u00b7ligent, les persianes tamb\u00e9 poden proporcionar beneficis addicionals de seguretat. Les persianes intel\u00b7ligents poden estar connectades a l&#8217;alarma de fum per a obrir-les autom\u00e0ticament quan es detecti un incendi a l&#8217;interior, permetent als serveis d&#8217;emerg\u00e8ncia veure l&#8217;interior de la casa.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><p><strong>Seguretat<\/strong><\/p><\/li><\/ul>\n\n\n\n<p>En poder-se controlar a dist\u00e0ncia o pel fet que es pot establir un horari que faci semblar que hi ha alg\u00fa a casa, les persianes intel\u00b7ligents poden ajudar a enganyar els possibles lladres perqu\u00e8 pensin que la casa est\u00e0 ocupada. De la mateixa manera, quan es connecten a un sistema dom\u00e8stic intel\u00b7ligent, les persianes poden tancar-se quan els ocupants es van i obrir-se quan tornen, nom\u00e9s configurant l&#8217;aplicaci\u00f3 en el teu tel\u00e8fon intel\u00b7ligent.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/alexander-tsang-Gi7W_mXTPGA-unsplash-edited-scaled.jpg\" alt=\"\" class=\"wp-image-24528\" width=\"460\" height=\"345\" srcset=\"https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/alexander-tsang-Gi7W_mXTPGA-unsplash-edited-scaled.jpg 2560w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/alexander-tsang-Gi7W_mXTPGA-unsplash-edited-300x225.jpg 300w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/alexander-tsang-Gi7W_mXTPGA-unsplash-edited-1024x769.jpg 1024w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/alexander-tsang-Gi7W_mXTPGA-unsplash-edited-768x577.jpg 768w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/alexander-tsang-Gi7W_mXTPGA-unsplash-edited-1536x1153.jpg 1536w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/alexander-tsang-Gi7W_mXTPGA-unsplash-edited-2048x1538.jpg 2048w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/alexander-tsang-Gi7W_mXTPGA-unsplash-edited-194x146.jpg 194w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/alexander-tsang-Gi7W_mXTPGA-unsplash-edited-50x38.jpg 50w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/alexander-tsang-Gi7W_mXTPGA-unsplash-edited-100x75.jpg 100w, https:\/\/www.carpinteria-aluminio.cat\/wp-content\/uploads\/2021\/02\/alexander-tsang-Gi7W_mXTPGA-unsplash-edited-960x720.jpg 960w\" sizes=\"auto, (max-width:767px) 460px, 460px\" \/><\/figure><\/div>\n\n\n\n<p>En comparaci\u00f3 amb moltes altres solucions d&#8217;estalvi d&#8217;energia per a la rehabilitaci\u00f3 o una nova construcci\u00f3, la instal\u00b7laci\u00f3 de persianes intel\u00b7ligents \u00e9s una forma relativament barata de controlar el guany solar i la p\u00e8rdua de calor en una casa. Aix\u00f2 fa que qualsevol constructor o propietari que vulgui aconseguir un habitatge el m\u00e9s ecol\u00f2gica possible, hagi de considerar-ho seriosament. A m\u00e9s, la integraci\u00f3 de la tecnologia intel\u00b7ligent augmenta la capacitat de les persianes motoritzades per a reduir l&#8217;\u00fas de l&#8217;energia i \u00e9s un excel\u00b7lent exemple de com la llar intel\u00b7ligent pot ser utilitzat per a ajudar a protegir el nostre planeta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per a qualsevol persona que construeixi o remodeli una casa, l&#8217;efici\u00e8ncia energ\u00e8tica \u00e9s un factor clau. Des de l&#8217;a\u00efllament fins a la ubicaci\u00f3, la manera de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":24516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[36],"tags":[],"class_list":["post-24614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.carpinteria-aluminio.cat\/ca\/wp-json\/wp\/v2\/posts\/24614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carpinteria-aluminio.cat\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carpinteria-aluminio.cat\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carpinteria-aluminio.cat\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carpinteria-aluminio.cat\/ca\/wp-json\/wp\/v2\/comments?post=24614"}],"version-history":[{"count":2,"href":"https:\/\/www.carpinteria-aluminio.cat\/ca\/wp-json\/wp\/v2\/posts\/24614\/revisions"}],"predecessor-version":[{"id":24875,"href":"https:\/\/www.carpinteria-aluminio.cat\/ca\/wp-json\/wp\/v2\/posts\/24614\/revisions\/24875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carpinteria-aluminio.cat\/ca\/wp-json\/wp\/v2\/media\/24516"}],"wp:attachment":[{"href":"https:\/\/www.carpinteria-aluminio.cat\/ca\/wp-json\/wp\/v2\/media?parent=24614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carpinteria-aluminio.cat\/ca\/wp-json\/wp\/v2\/categories?post=24614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carpinteria-aluminio.cat\/ca\/wp-json\/wp\/v2\/tags?post=24614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}